{"id":18487,"date":"2015-07-23T16:24:36","date_gmt":"2015-07-23T16:24:36","guid":{"rendered":"https:\/\/cdd.devtest.host\/?p=18487"},"modified":"2025-01-07T16:25:09","modified_gmt":"2025-01-07T16:25:09","slug":"mission-de-la-caisse-des-depots-et-des-consignations","status":"publish","type":"post","link":"https:\/\/cdd.gov.mr\/fr\/2015\/07\/23\/mission-de-la-caisse-des-depots-et-des-consignations\/","title":{"rendered":"Mission de la Caisse des D\u00e9p\u00f4ts et des Consignations"},"content":{"rendered":"\n<p>Sur invitation de la Caisse des D\u00e9p\u00f4ts et de D\u00e9veloppement (CDD), Monsieur Christian BADAUT, Responsable du P\u00f4le International \u00e0 la Caisse des D\u00e9p\u00f4ts et de Consignations (CDC) de la France, a s\u00e9journ\u00e9 en Mauritanie du 20 au 22 juillet 2015, \u00e0 l\u2019effet de discuter de la r\u00e9alisation d\u2019un accord de coop\u00e9ration entre les deux institutions visant \u00e0 d\u00e9velopper des activit\u00e9s op\u00e9rationnelles par la&nbsp; mise en \u0153uvre de projets d\u2019int\u00e9r\u00eat commun.<\/p>\n\n\n\n<p><strong>Rappel<\/strong><\/p>\n\n\n\n<p>La CDC a accompagn\u00e9 en 2010 la r\u00e9flexion des autorit\u00e9s mauritaniennes sur la cr\u00e9ation d&rsquo;une Caisse des D\u00e9p\u00f4ts, notamment par une \u00e9tude de faisabilit\u00e9.<\/p>\n\n\n\n<p>La&nbsp; CDD et la CDC entretiennent des \u00e9changes techniques r\u00e9guliers \u00e0 Nouakchott et \u00e0 Paris depuis la cr\u00e9ation de la nouvelle institution en mars 2011.<\/p>\n\n\n\n<p>Elles coop\u00e8rent \u00e9galement dans le cadre du Forum Mondial des Caisses de D\u00e9p\u00f4t, dont les priorit\u00e9s sont le financement des entreprises, les infrastructures, le d\u00e9veloppement urbain et le logement social, ainsi que le d\u00e9veloppement institutionnel.<\/p>\n\n\n\n<p>La CDD et la CDC, d\u00e9sireuses de formaliser leurs \u00e9changes et contacts, conviennent d\u2019\u00e9tablir le pr\u00e9sent accord de coop\u00e9ration triennal, dans le respect de leurs missions d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral et de leur identit\u00e9 d\u2019investisseurs de long terme au service du d\u00e9veloppement de leurs pays respectifs.<\/p>\n\n\n\n<p><em><u>Les discussions ont port\u00e9es sur<\/u><\/em>&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Coop\u00e9ration multilat\u00e9rale<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Elle portera&nbsp; sur le financement de long terme des infrastructures, du logement et des entreprises, dans le cadre des groupes de travail th\u00e9matiques, mis en place lors du 2<sup>\u00e8me<\/sup>&nbsp;Forum Mondial des Caisses de D\u00e9p\u00f4t du 19 avril 2013 \u00e0 Paris, dont les premi\u00e8res orientations strat\u00e9giques ont \u00e9t\u00e9 pr\u00e9sent\u00e9es au 3<sup>\u00e8me<\/sup>&nbsp;Forum du 17 avril 2015 \u00e0 Tunis et seront approfondies au 4<sup>\u00e8me<\/sup>&nbsp;Forum de Rome en 2017.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Coop\u00e9ration institutionnelle<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Afin d\u2019appuyer son d\u00e9veloppement, la CDC et la CDD d\u00e9velopperont des \u00e9changes techniques et organiseront des missions, \u00e0 Paris et \u00e0 Nouakchott, ainsi que des ateliers th\u00e9matiques par l\u2019accueil \u00e0 Paris de repr\u00e9sentants de la CDD au sein des \u00e9quipes de la CDC, principalement sur : l&rsquo;activit\u00e9 de mandataire,&nbsp; la gestion du bilan et le mod\u00e8le prudentiel et la filialisation des activit\u00e9s.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Grands projets de d\u00e9veloppement \u00e9conomique et social\u00a0:<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9veloppement de l&rsquo;offre de logements sociaux (livrets d\u2019\u00e9pargne centralis\u00e9s et instruments innovants)\u00a0;<\/strong><\/li>\n\n\n\n<li><strong>Financement des PME et de la Tr\u00e8s Petite Entreprise (TPE);<\/strong><\/li>\n\n\n\n<li><strong>Infrastructures\u00a0:\u00a0<\/strong>\u00e9changes techniques approfondis sur les modalit\u00e9s de r\u00e9alisation et de financement des infrastructures, en examinant en priorit\u00e9 les projets int\u00e9ressant ou port\u00e9s par la CDD.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><strong>L\u2019accord conclu pour 3 ans entrera en vigueur \u00e0 compter de sa date de signature par les Directeurs G\u00e9n\u00e9raux de la CDD et de la CDC.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur invitation de la Caisse des D\u00e9p\u00f4ts et de D\u00e9veloppement (CDD), Monsieur Christian BADAUT, Responsable du P\u00f4le International \u00e0 la Caisse des D\u00e9p\u00f4ts et de Consignations (CDC) de la France, a s\u00e9journ\u00e9 en Mauritanie du 20 au 22 juillet 2015, \u00e0 l\u2019effet de discuter de la r\u00e9alisation d\u2019un accord de coop\u00e9ration entre les deux institutions<\/p>\n","protected":false},"author":1,"featured_media":18488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-18487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/comments?post=18487"}],"version-history":[{"count":1,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18487\/revisions"}],"predecessor-version":[{"id":18489,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18487\/revisions\/18489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/media\/18488"}],"wp:attachment":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/media?parent=18487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/categories?post=18487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/tags?post=18487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}