{"id":18472,"date":"2017-09-19T16:08:30","date_gmt":"2017-09-19T16:08:30","guid":{"rendered":"https:\/\/cdd.devtest.host\/?p=18472"},"modified":"2025-01-07T16:08:54","modified_gmt":"2025-01-07T16:08:54","slug":"signature-dune-convention-de-partenariat-entre-la-cdd-et-la-cdg-du-maroc","status":"publish","type":"post","link":"https:\/\/cdd.gov.mr\/fr\/2017\/09\/19\/signature-dune-convention-de-partenariat-entre-la-cdd-et-la-cdg-du-maroc\/","title":{"rendered":"Signature d\u2019une convention de partenariat entre la CDD et la CDG du Maroc"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>&nbsp;S&rsquo;inscrivant dans la poursuite des relations d&rsquo;excellence entre le Royaume du Maroc et la R\u00e9publique&nbsp;Islamique de Mauritanie, la Caisse de D\u00e9p\u00f4t et de Gestion du Maroc (CDG) et la Caisse des D\u00e9p\u00f4ts et de D\u00e9veloppement de la R\u00e9publique Islamique de Mauritanie (CDD) ont depuis 2011 initi\u00e9 et d\u00e9velopp\u00e9 des \u00e9changes techniques et des contacts r\u00e9guliers \u00e0 Nouakchott et \u00e0 Rabat.Dans le cadre du renforcement de leur coop\u00e9ration bilat\u00e9rale, les deux institutions se sont rapproch\u00e9es aux fins de formaliser un accord de coop\u00e9ration dans le respect des missions d&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral qui leur sont assign\u00e9es, de leur r\u00f4le d&rsquo;investisseur de long terme et de leur qualit\u00e9 de catalyseur du secteur priv\u00e9.A ce titre, les Directeurs G\u00e9n\u00e9raux de la CDG et de la CDD ont proc\u00e9d\u00e9, le 19 septembre 2017, \u00e0 la&nbsp;signature d\u2019une convention de partenariat aux fins de d\u00e9velopper leur coop\u00e9ration, de mobiliser leurs comp\u00e9tences pour la r\u00e9alisation de projets et de programmes ainsi que d\u2019\u00e9changes techniques, dans diff\u00e9rents domaines d\u2019int\u00e9r\u00eat commun, dont notamment le mod\u00e8le prudentiel de caisse de d\u00e9p\u00f4t et la gestion de l\u2019\u00e9pargne.Les parties ont \u00e9galement convenu de mettre en place un comit\u00e9 de coordination pr\u00e9sid\u00e9 par les&nbsp;Secr\u00e9taires G\u00e9n\u00e9raux respectifs de la CDG et de la CDD, d\u00e9di\u00e9 principalement \u00e0 \u00e9tablir la programmation des actions et \u00e0 assurer le suivi des r\u00e9alisations.<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;S&rsquo;inscrivant dans la poursuite des relations d&rsquo;excellence entre le Royaume du Maroc et la R\u00e9publique&nbsp;Islamique de Mauritanie, la Caisse de D\u00e9p\u00f4t et de Gestion du Maroc (CDG) et la Caisse des D\u00e9p\u00f4ts et de D\u00e9veloppement de la R\u00e9publique Islamique de Mauritanie (CDD) ont depuis 2011 initi\u00e9 et d\u00e9velopp\u00e9 des \u00e9changes techniques et des contacts r\u00e9guliers<\/p>\n","protected":false},"author":1,"featured_media":18473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-18472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/comments?post=18472"}],"version-history":[{"count":1,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18472\/revisions"}],"predecessor-version":[{"id":18474,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18472\/revisions\/18474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/media\/18473"}],"wp:attachment":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/media?parent=18472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/categories?post=18472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/tags?post=18472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}