{"id":18464,"date":"2019-02-19T16:00:28","date_gmt":"2019-02-19T16:00:28","guid":{"rendered":"https:\/\/cdd.devtest.host\/?p=18464"},"modified":"2025-01-07T16:01:13","modified_gmt":"2025-01-07T16:01:13","slug":"visite-de-travail-dune-delegation-de-lenda-senegal","status":"publish","type":"post","link":"https:\/\/cdd.gov.mr\/fr\/2019\/02\/19\/visite-de-travail-dune-delegation-de-lenda-senegal\/","title":{"rendered":"Visite de travail d&rsquo;une d\u00e9l\u00e9gation de l\u2019ENDA-S\u00e9n\u00e9gal"},"content":{"rendered":"\n<p>Le Directeur G\u00e9n\u00e9ral de la Caisse des D\u00e9p\u00f4ts et de D\u00e9veloppement (CDD) a re\u00e7u en audience ce mardi 19 f\u00e9vrier 2019 une d\u00e9l\u00e9gation de l\u2019organisation internationale ENDA-S\u00e9n\u00e9gal conduite par Monsieur Mamadou Bachir KANOUTE, Coordinateur Ex\u00e9cutif de ENDA ECOPOP et comprenant Monsieur Oumar TANDIA Coordonnateur de ENDA ECOPOLE et Monsieur Secou SARR Directeur de ENDA ENERGIE.<\/p>\n\n\n\n<p><br>Cette rencontre a port\u00e9 sur les possibilit\u00e9s de partenariat entre la CDD et cette organisation notamment dans le domaine de la mise en \u0153uvre des Objectifs de D\u00e9veloppement Durable (ODD). La rencontre a port\u00e9 en particulier sur les possibilit\u00e9s de promotion de l\u2019incubation des cat\u00e9gories \u201cjeunes\u201d dans le cadre d\u2019un \u00e9cosyst\u00e8me o\u00f9 l\u2019ENDA s\u2019investirait dans le domaine de la prise en charge des services non marchands et la CDD en mati\u00e8re d\u2019appui en financement.<br>La r\u00e9union s\u2019est d\u00e9roul\u00e9e en pr\u00e9sence du Directeur du D\u00e9veloppement Monsieur Mohamed Abdellahi OULD LEMRABOTT.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Directeur G\u00e9n\u00e9ral de la Caisse des D\u00e9p\u00f4ts et de D\u00e9veloppement (CDD) a re\u00e7u en audience ce mardi 19 f\u00e9vrier 2019 une d\u00e9l\u00e9gation de l\u2019organisation internationale ENDA-S\u00e9n\u00e9gal conduite par Monsieur Mamadou Bachir KANOUTE, Coordinateur Ex\u00e9cutif de ENDA ECOPOP et comprenant Monsieur Oumar TANDIA Coordonnateur de ENDA ECOPOLE et Monsieur Secou SARR Directeur de ENDA ENERGIE.<\/p>\n","protected":false},"author":1,"featured_media":18465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-18464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/comments?post=18464"}],"version-history":[{"count":1,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18464\/revisions"}],"predecessor-version":[{"id":18466,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18464\/revisions\/18466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/media\/18465"}],"wp:attachment":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/media?parent=18464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/categories?post=18464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/tags?post=18464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}