{"id":18417,"date":"2023-03-10T13:23:28","date_gmt":"2023-03-10T13:23:28","guid":{"rendered":"https:\/\/cdd.devtest.host\/?p=18417"},"modified":"2025-01-15T12:11:53","modified_gmt":"2025-01-15T12:11:53","slug":"participation-du-directeur-general-de-la-cdd-a-un-panel-sur-linclusion-financiere","status":"publish","type":"post","link":"https:\/\/cdd.gov.mr\/fr\/2023\/03\/10\/participation-du-directeur-general-de-la-cdd-a-un-panel-sur-linclusion-financiere\/","title":{"rendered":"PARTICIPATION DU DIRECTEUR GENERAL DE LA CDD A UN PANEL SUR L\u2019INCLUSION FINANCIERE"},"content":{"rendered":"\n<p>La Banque Centrale de Mauritanie a organis\u00e9, en collaboration avec le bureau du Fonds Mon\u00e9taire International en Mauritanie et l\u2019Universit\u00e9 de Nouakchott, un panel sur l\u2019inclusion financi\u00e8re, le vendredi 10 mars au Palais des Congr\u00e8s, en pr\u00e9sence du Directeur G\u00e9n\u00e9ral Adjoint du Fonds Mon\u00e9taire International, Monsieur Kenji Okamura. Le sujet de la discussion \u00e9tait focalis\u00e9 sur le chapitre 7 du rapport du FMI portant sur l\u2019inclusion financi\u00e8re&nbsp;: promouvoir une croissance inclusive au Moyen-Orient et en Afrique du Nord, d\u00e9fis et opportunit\u00e9s apr\u00e8s la pand\u00e9mie.<\/p>\n\n\n\n<p>Le panel \u00e9tait compos\u00e9 de&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Docteur Mohamed Lemine Dhehby, Gouverneur de la BCM<\/li>\n\n\n\n<li>Monsieur Mohamadou Youssouf Diagana, Directeur G\u00e9n\u00e9ral de la CDD<\/li>\n\n\n\n<li>Madame Anta Ndoye, Repr\u00e9sentante R\u00e9sidente du FMI en Mauritanie<\/li>\n\n\n\n<li>Madame Zeinabou Abdeljelil, Fondatrice de Hadina RIMTIC<\/li>\n\n\n\n<li>Madame Aissata Lam, Directrice G\u00e9n\u00e9rale de l\u2019APIM<\/li>\n<\/ul>\n\n\n\n<p>Apr\u00e8s les discours d\u2019ouverture du Pr\u00e9sident de l\u2019Universit\u00e9 de Nouakchott et du DGA du FMI, une pr\u00e9sentation sur l\u2019inclusion financi\u00e8re a \u00e9t\u00e9 faite par la Repr\u00e9sentante R\u00e9sidente du FMI. Le DG de la CDD a rappel\u00e9 que le taux \u00e9tait relativement bas, mais qu\u2019il faut cependant noter que la strat\u00e9gie d\u2019inclusion financi\u00e8re du gouvernement est en cours de d\u00e9veloppement.&nbsp;<\/p>\n\n\n\n<p>Le panel s\u2019est conclu par un \u00e9change entre les \u00e9tudiants pr\u00e9sents et les pan\u00e9listes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Banque Centrale de Mauritanie a organis\u00e9, en collaboration avec le bureau du Fonds Mon\u00e9taire International en Mauritanie et l\u2019Universit\u00e9 de Nouakchott, un panel sur l\u2019inclusion financi\u00e8re, le vendredi 10 mars au Palais des Congr\u00e8s, en pr\u00e9sence du Directeur G\u00e9n\u00e9ral Adjoint du Fonds Mon\u00e9taire International, Monsieur Kenji Okamura. Le sujet de la discussion \u00e9tait focalis\u00e9<\/p>\n","protected":false},"author":1,"featured_media":18418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-18417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/comments?post=18417"}],"version-history":[{"count":1,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18417\/revisions"}],"predecessor-version":[{"id":18419,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/posts\/18417\/revisions\/18419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/media\/18418"}],"wp:attachment":[{"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/media?parent=18417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/categories?post=18417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdd.gov.mr\/fr\/wp-json\/wp\/v2\/tags?post=18417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}